{"id":2428,"count":1,"description":"good practices","link":"https:\/\/minuartia.com\/en\/tag\/good-practices-en\/","name":"good practices","slug":"good-practices-en","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arxius de good practices | Minuartia<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arxius de good practices | Minuartia\" \/>\n<meta property=\"og:description\" content=\"good practices\" \/>\n<meta property=\"og:url\" content=\"https:\/\/minuartia.com\/en\/tag\/good-practices-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Minuartia\" \/>\n<meta property=\"og:image\" content=\"https:\/\/minuartia.com\/wp-content\/uploads\/2023\/10\/bosque3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"807\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@minuartia_tw\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/minuartia.com\\\/en\\\/tag\\\/good-practices-en\\\/\",\"url\":\"https:\\\/\\\/minuartia.com\\\/en\\\/tag\\\/good-practices-en\\\/\",\"name\":\"Arxius de good practices | Minuartia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/minuartia.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/minuartia.com\\\/en\\\/tag\\\/good-practices-en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/minuartia.com\\\/en\\\/tag\\\/good-practices-en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/minuartia.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"good practices\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/minuartia.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/minuartia.com\\\/en\\\/\",\"name\":\"Minuartia\",\"description\":\"Gesti\u00f3 i Conservaci\u00f3 de Fauna i Biodiversitat.\",\"publisher\":{\"@id\":\"https:\\\/\\\/minuartia.com\\\/en\\\/#organization\"},\"alternateName\":\"Coneixement aplicat en biodiversitat i gesti\u00f3 de fauna\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/minuartia.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/minuartia.com\\\/en\\\/#organization\",\"name\":\"Minuartia\",\"alternateName\":\"Minuartia\",\"url\":\"https:\\\/\\\/minuartia.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/minuartia.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/minuartia.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/OG-logo-MINUARTIA-RGB_transparent.png\",\"contentUrl\":\"https:\\\/\\\/minuartia.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/OG-logo-MINUARTIA-RGB_transparent.png\",\"width\":1570,\"height\":701,\"caption\":\"Minuartia\"},\"image\":{\"@id\":\"https:\\\/\\\/minuartia.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/minuartia_tw\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/MINUARTIAwildlife?sub_confirmation=1\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arxius de good practices | Minuartia","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Arxius de good practices | Minuartia","og_description":"good practices","og_url":"https:\/\/minuartia.com\/en\/tag\/good-practices-en\/","og_site_name":"Minuartia","og_image":[{"width":1280,"height":807,"url":"https:\/\/minuartia.com\/wp-content\/uploads\/2023\/10\/bosque3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@minuartia_tw","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/minuartia.com\/en\/tag\/good-practices-en\/","url":"https:\/\/minuartia.com\/en\/tag\/good-practices-en\/","name":"Arxius de good practices | Minuartia","isPartOf":{"@id":"https:\/\/minuartia.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/minuartia.com\/en\/tag\/good-practices-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/minuartia.com\/en\/tag\/good-practices-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/minuartia.com\/en\/"},{"@type":"ListItem","position":2,"name":"good practices"}]},{"@type":"WebSite","@id":"https:\/\/minuartia.com\/en\/#website","url":"https:\/\/minuartia.com\/en\/","name":"Minuartia","description":"Gesti\u00f3 i Conservaci\u00f3 de Fauna i Biodiversitat.","publisher":{"@id":"https:\/\/minuartia.com\/en\/#organization"},"alternateName":"Coneixement aplicat en biodiversitat i gesti\u00f3 de fauna","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/minuartia.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/minuartia.com\/en\/#organization","name":"Minuartia","alternateName":"Minuartia","url":"https:\/\/minuartia.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/minuartia.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/minuartia.com\/wp-content\/uploads\/2023\/09\/OG-logo-MINUARTIA-RGB_transparent.png","contentUrl":"https:\/\/minuartia.com\/wp-content\/uploads\/2023\/09\/OG-logo-MINUARTIA-RGB_transparent.png","width":1570,"height":701,"caption":"Minuartia"},"image":{"@id":"https:\/\/minuartia.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/minuartia_tw","https:\/\/www.youtube.com\/user\/MINUARTIAwildlife?sub_confirmation=1"]}]}},"_links":{"self":[{"href":"https:\/\/minuartia.com\/en\/wp-json\/wp\/v2\/tags\/2428","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/minuartia.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/minuartia.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/minuartia.com\/en\/wp-json\/wp\/v2\/posts?tags=2428"},{"href":"https:\/\/minuartia.com\/en\/wp-json\/wp\/v2\/team?tags=2428"},{"href":"https:\/\/minuartia.com\/en\/wp-json\/wp\/v2\/project?tags=2428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}